{"id":5706,"date":"2023-11-29T18:00:08","date_gmt":"2023-11-29T18:00:08","guid":{"rendered":"https:\/\/eltiosam.com.mx\/?post_type=product&#038;p=5706"},"modified":"2024-02-14T01:40:22","modified_gmt":"2024-02-14T01:40:22","slug":"lavadora-lg-wm22vv2s6r-22-kg","status":"publish","type":"product","link":"https:\/\/eltiosam.com.mx\/index.php\/product\/lavadora-lg-wm22vv2s6r-22-kg\/","title":{"rendered":"Lavadora LG &#8211; WM22VV2S6R &#8211; 22 Kg"},"content":{"rendered":"<p><strong>Descripci\u00f3n:<\/strong><\/p>\n<p>Protege tu ropa con inteligencia artificial que detecta las caracteristicas para determinar el patron de lavado mas optimo para tus prendas. Turbo wash 360 rociadores adicionales de agua que lavan a profundidad las cargas mas pesadas. 6 motion dd 6 moviemientos de la tina para el cuidado optimo de la ropa. Steam elimina 99% de alergenos tales como acaros que pueden cauar alergia o enfermedades respiratorias. Lg thinq controla tu equipo desde tu smarthone. Smart diagnosis realiza un diagnostico de tu equipo desde tu smartphone. Motor lg direct drive 10 a\u00f1os de garantia en el motor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descripci\u00f3n: Protege tu ropa con inteligencia artificial que detecta las caracteristicas para determinar el patron de lavado mas optimo para tus prendas. Turbo wash 360 rociadores adicionales de agua que lavan a profundidad las cargas mas pesadas. 6 motion dd 6 moviemientos de la tina para el cuidado optimo de la ropa. Steam elimina 99% [&hellip;]<\/p>\n","protected":false},"featured_media":5707,"template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[180],"product_tag":[208],"class_list":["post-5706","product","type-product","status-publish","has-post-thumbnail","product_cat-lavadoras-carga-frontal","product_tag-lg","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/eltiosam.com.mx\/index.php\/wp-json\/wp\/v2\/product\/5706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eltiosam.com.mx\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eltiosam.com.mx\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eltiosam.com.mx\/index.php\/wp-json\/wp\/v2\/media\/5707"}],"wp:attachment":[{"href":"https:\/\/eltiosam.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=5706"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/eltiosam.com.mx\/index.php\/wp-json\/wp\/v2\/product_brand?post=5706"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eltiosam.com.mx\/index.php\/wp-json\/wp\/v2\/product_cat?post=5706"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eltiosam.com.mx\/index.php\/wp-json\/wp\/v2\/product_tag?post=5706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}